{"id":5,"count":5,"description":"","link":"https:\/\/www.insatsuyasan.com\/blog\/category\/%e3%83%bb%e6%9c%ac%e3%82%92%e8%aa%ad%e3%82%93%e3%81%a7","name":"\u30fb\u672c\u3092\u8aad\u3093\u3067","slug":"%e3%83%bb%e6%9c%ac%e3%82%92%e8%aa%ad%e3%82%93%e3%81%a7","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.insatsuyasan.com\/blog\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.insatsuyasan.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.insatsuyasan.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.insatsuyasan.com\/blog\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}